{"id":10000655,"date":"2026-07-15T10:04:11","date_gmt":"2026-07-15T08:04:11","guid":{"rendered":"https:\/\/www.be.life\/event\/be-klangbad-present\/"},"modified":"2026-07-15T10:04:11","modified_gmt":"2026-07-15T08:04:11","slug":"be-klangbad-present","status":"publish","type":"tribe_events","link":"https:\/\/www.be.life\/de\/event\/be-klangbad-present\/2027-02-11\/","title":{"rendered":"Be: Klangbad \u201ePresent\u201c"},"content":{"rendered":"<p>Ein wohltuendes Klangheilungserlebnis, das Ihnen dabei helfen soll, zur Ruhe zu kommen, wieder zu sich selbst zu finden und in den gegenw\u00e4rtigen Moment zur\u00fcckzukehren. Durch Meditation, Kristall- und tibetische Klangschalen sowie beruhigende therapeutische Kl\u00e4nge werden Sie in einen Raum tiefer Entspannung, innerer Stille und sanfter Losl\u00f6sung eingeladen. <\/p>\n<p><a href=\"https:\/\/www.be.life\/de\/buchen\/\"><strong>BUCH<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein wohltuendes Klangheilungserlebnis, das Ihnen dabei helfen soll, zur Ruhe zu kommen, wieder zu sich selbst zu finden und in den gegenw\u00e4rtigen Moment zur\u00fcckzukehren. Durch Meditation, Kristall- und tibetische Klangschalen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4462,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[68,70],"class_list":["post-10000655","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-klangbader","tribe_events_cat-wochentliche-sitzungen","cat_klangbader","cat_wochentliche-sitzungen","tribe-recurring-event","tribe-recurring-event-parent"],"_links":{"self":[{"href":"https:\/\/www.be.life\/de\/wp-json\/wp\/v2\/tribe_events\/10000655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.be.life\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.be.life\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.be.life\/de\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/www.be.life\/de\/wp-json\/wp\/v2\/tribe_events\/10000655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.be.life\/de\/wp-json\/wp\/v2\/media\/4462"}],"wp:attachment":[{"href":"https:\/\/www.be.life\/de\/wp-json\/wp\/v2\/media?parent=10000655"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.be.life\/de\/wp-json\/wp\/v2\/tags?post=10000655"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.be.life\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=10000655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}